{"id":274,"count":1,"description":"","link":"https:\/\/melissapontery.fr\/index.php\/tag\/opera\/","name":"Op\u00e9ra","slug":"opera","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Op\u00e9ra - M\u00e9lissa Pont\u00e9ry<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/melissapontery.fr\/index.php\/tag\/opera\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Op\u00e9ra - M\u00e9lissa Pont\u00e9ry\" \/>\n<meta property=\"og:url\" content=\"https:\/\/melissapontery.fr\/index.php\/tag\/opera\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e9lissa Pont\u00e9ry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/melissapontery.fr\\\/index.php\\\/tag\\\/opera\\\/\",\"url\":\"https:\\\/\\\/melissapontery.fr\\\/index.php\\\/tag\\\/opera\\\/\",\"name\":\"Archives des Op\u00e9ra - M\u00e9lissa Pont\u00e9ry\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/melissapontery.fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/melissapontery.fr\\\/index.php\\\/tag\\\/opera\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/melissapontery.fr\\\/index.php\\\/tag\\\/opera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/melissapontery.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\\\/\\\/melissapontery.fr\\\/index.php\\\/articles\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Op\u00e9ra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/melissapontery.fr\\\/#website\",\"url\":\"https:\\\/\\\/melissapontery.fr\\\/\",\"name\":\"M\u00e9lissa Pont\u00e9ry\",\"description\":\"Autrice, R\u00e9dactrice et Lectrice\",\"publisher\":{\"@id\":\"https:\\\/\\\/melissapontery.fr\\\/#\\\/schema\\\/person\\\/879d99a7ed8522fc4c9aba2d2e3b615c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/melissapontery.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/melissapontery.fr\\\/#\\\/schema\\\/person\\\/879d99a7ed8522fc4c9aba2d2e3b615c\",\"name\":\"M\u00e9lissa Pont\u00e9ry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/iksscaz.cluster031.hosting.ovh.net\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/A-propos-5.png\",\"url\":\"http:\\\/\\\/iksscaz.cluster031.hosting.ovh.net\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/A-propos-5.png\",\"contentUrl\":\"http:\\\/\\\/iksscaz.cluster031.hosting.ovh.net\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/A-propos-5.png\",\"width\":550,\"height\":550,\"caption\":\"M\u00e9lissa Pont\u00e9ry\"},\"logo\":{\"@id\":\"http:\\\/\\\/iksscaz.cluster031.hosting.ovh.net\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/A-propos-5.png\"},\"sameAs\":[\"https:\\\/\\\/www.melissapontery.fr\",\"@melissa.pontery.auteure\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Op\u00e9ra - M\u00e9lissa Pont\u00e9ry","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/melissapontery.fr\/index.php\/tag\/opera\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des Op\u00e9ra - M\u00e9lissa Pont\u00e9ry","og_url":"https:\/\/melissapontery.fr\/index.php\/tag\/opera\/","og_site_name":"M\u00e9lissa Pont\u00e9ry","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/melissapontery.fr\/index.php\/tag\/opera\/","url":"https:\/\/melissapontery.fr\/index.php\/tag\/opera\/","name":"Archives des Op\u00e9ra - M\u00e9lissa Pont\u00e9ry","isPartOf":{"@id":"https:\/\/melissapontery.fr\/#website"},"breadcrumb":{"@id":"https:\/\/melissapontery.fr\/index.php\/tag\/opera\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/melissapontery.fr\/index.php\/tag\/opera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/melissapontery.fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/melissapontery.fr\/index.php\/articles\/"},{"@type":"ListItem","position":3,"name":"Op\u00e9ra"}]},{"@type":"WebSite","@id":"https:\/\/melissapontery.fr\/#website","url":"https:\/\/melissapontery.fr\/","name":"M\u00e9lissa Pont\u00e9ry","description":"Autrice, R\u00e9dactrice et Lectrice","publisher":{"@id":"https:\/\/melissapontery.fr\/#\/schema\/person\/879d99a7ed8522fc4c9aba2d2e3b615c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/melissapontery.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/melissapontery.fr\/#\/schema\/person\/879d99a7ed8522fc4c9aba2d2e3b615c","name":"M\u00e9lissa Pont\u00e9ry","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/iksscaz.cluster031.hosting.ovh.net\/wp-content\/uploads\/2022\/02\/A-propos-5.png","url":"http:\/\/iksscaz.cluster031.hosting.ovh.net\/wp-content\/uploads\/2022\/02\/A-propos-5.png","contentUrl":"http:\/\/iksscaz.cluster031.hosting.ovh.net\/wp-content\/uploads\/2022\/02\/A-propos-5.png","width":550,"height":550,"caption":"M\u00e9lissa Pont\u00e9ry"},"logo":{"@id":"http:\/\/iksscaz.cluster031.hosting.ovh.net\/wp-content\/uploads\/2022\/02\/A-propos-5.png"},"sameAs":["https:\/\/www.melissapontery.fr","@melissa.pontery.auteure"]}]}},"_links":{"self":[{"href":"https:\/\/melissapontery.fr\/index.php\/wp-json\/wp\/v2\/tags\/274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/melissapontery.fr\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/melissapontery.fr\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/melissapontery.fr\/index.php\/wp-json\/wp\/v2\/posts?tags=274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}